{"id":814,"count":13,"description":"","link":"https:\/\/www.usmotorworks.com\/mx\/categoria-producto\/derale\/performance-fuel-pumps-2\/performance-fuel-pumps\/","name":"Bombas de combustible de alto rendimiento","slug":"performance-fuel-pumps","taxonomy":"product_cat","parent":838,"meta":[],"menu_order":142,"acf":[],"_links":{"self":[{"href":"https:\/\/www.usmotorworks.com\/mx\/wp-json\/wp\/v2\/product_cat\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.usmotorworks.com\/mx\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.usmotorworks.com\/mx\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.usmotorworks.com\/mx\/wp-json\/wp\/v2\/product_cat\/838"}],"wp:post_type":[{"href":"https:\/\/www.usmotorworks.com\/mx\/wp-json\/wp\/v2\/product?product_cat=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}